{"id":2826,"date":"2026-04-14T08:25:13","date_gmt":"2026-04-14T06:25:13","guid":{"rendered":"https:\/\/radiounion.es\/?p=2826"},"modified":"2026-04-14T10:48:31","modified_gmt":"2026-04-14T08:48:31","slug":"lo-nuestro-la-copla-11-de-abril-2026","status":"publish","type":"post","link":"http:\/\/radiounion.es\/index.php\/2026\/04\/14\/lo-nuestro-la-copla-11-de-abril-2026\/","title":{"rendered":"Lo Nuestro la Copla 11 de abril 2026"},"content":{"rendered":"<p>Cada s\u00e1bado y domingo de 8 a 10 de la ma\u00f1ana la mejor m\u00fasica en espa\u00f1ol, copla, canci\u00f3n espa\u00f1ola, flamenco. Disfruta cada fin de semana de Lo Nuestro la Copla con Nagore Chiscano o vuelve a escucharlo donde y cuando quieras.<br \/>\n<iframe style=\"width: 100%;\" src=\"https:\/\/www.ivoox.com\/player_ej_171831848_6_1.html?c1=f45c34\" height=\"200\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cada s\u00e1bado y domingo de 8 a 10 de la ma\u00f1ana la mejor m\u00fasica en espa\u00f1ol, copla, canci\u00f3n espa\u00f1ola, flamenco. Disfruta cada fin de semana de Lo Nuestro la Copla con Nagore Chiscano o vuelve a escucharlo donde y cuando quieras.<\/p>\n","protected":false},"author":2,"featured_media":1992,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-2826","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pcd-lo-nuestro-la-copla"],"_links":{"self":[{"href":"http:\/\/radiounion.es\/index.php\/wp-json\/wp\/v2\/posts\/2826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/radiounion.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/radiounion.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/radiounion.es\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/radiounion.es\/index.php\/wp-json\/wp\/v2\/comments?post=2826"}],"version-history":[{"count":2,"href":"http:\/\/radiounion.es\/index.php\/wp-json\/wp\/v2\/posts\/2826\/revisions"}],"predecessor-version":[{"id":2833,"href":"http:\/\/radiounion.es\/index.php\/wp-json\/wp\/v2\/posts\/2826\/revisions\/2833"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/radiounion.es\/index.php\/wp-json\/wp\/v2\/media\/1992"}],"wp:attachment":[{"href":"http:\/\/radiounion.es\/index.php\/wp-json\/wp\/v2\/media?parent=2826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/radiounion.es\/index.php\/wp-json\/wp\/v2\/categories?post=2826"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/radiounion.es\/index.php\/wp-json\/wp\/v2\/tags?post=2826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}